{"id":9,"count":1,"description":"","link":"https:\/\/aguaattiva.com.br\/en_za\/categoria\/mineralle\/","name":"Mineralle","slug":"mineralle","taxonomy":"categoria","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.4 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arquivo de Mineralle - aguaattiva.com.br<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aguaattiva.com.br\/en_za\/categoria\/mineralle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Mineralle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aguaattiva.com.br\/en_za\/categoria\/mineralle\/\" \/>\n<meta property=\"og:site_name\" content=\"aguaattiva.com.br\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/categoria\\\/mineralle\\\/\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/categoria\\\/mineralle\\\/\",\"name\":\"Arquivo de Mineralle - aguaattiva.com.br\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/categoria\\\/mineralle\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/categoria\\\/mineralle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/aguaattiva.com.br\\\/pt_br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mineralle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#website\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/\",\"name\":\"Agua Mineral Natural Attiva\",\"description\":\"\u00c1gua Mineral Attiva \u00e9 sin\u00f4nimo de pureza, qualidade e compromisso com a sa\u00fade e bem-estar dos nossos consumidores. Extra\u00edda de fontes cuidadosamente protegidas, nossa \u00e1gua passa por rigorosos controles de qualidade para garantir um produto leve, refrescante e naturalmente equilibrado em sais minerais.  Atuamos no mercado com responsabilidade ambiental e excel\u00eancia em cada etapa da produ\u00e7\u00e3o e distribui\u00e7\u00e3o. Oferecemos uma linha completa para atender diferentes necessidades: 510ml, 1500ml, 5L e 20L, ideal para o dia a dia, empresas, eventos e estabelecimentos comerciais.  Nossa miss\u00e3o \u00e9 levar hidrata\u00e7\u00e3o de qualidade a todos os lares, com respeito \u00e0 natureza e dedica\u00e7\u00e3o ao cliente. Acreditamos que cuidar da sua sa\u00fade come\u00e7a com uma escolha simples: beber bem, beber Attiva.\",\"publisher\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#organization\"},\"alternateName\":\"Agua Attiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aguaattiva.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#organization\",\"name\":\"Grupo Attiva\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/agua_attiva-400-e1694737808635.png\",\"contentUrl\":\"https:\\\/\\\/aguaattiva.com.br\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/agua_attiva-400-e1694737808635.png\",\"width\":400,\"height\":400,\"caption\":\"Grupo Attiva\"},\"image\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AguaAttiva\",\"https:\\\/\\\/www.instagram.com\\\/aguaattiva\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arquivo de Mineralle - aguaattiva.com.br","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aguaattiva.com.br\/en_za\/categoria\/mineralle\/","og_locale":"en_US","og_type":"article","og_title":"Arquivo de Mineralle","og_url":"https:\/\/aguaattiva.com.br\/en_za\/categoria\/mineralle\/","og_site_name":"aguaattiva.com.br","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aguaattiva.com.br\/categoria\/mineralle\/","url":"https:\/\/aguaattiva.com.br\/categoria\/mineralle\/","name":"Arquivo de Mineralle - aguaattiva.com.br","isPartOf":{"@id":"https:\/\/aguaattiva.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/aguaattiva.com.br\/categoria\/mineralle\/#breadcrumb"},"inLanguage":"en-ZA"},{"@type":"BreadcrumbList","@id":"https:\/\/aguaattiva.com.br\/categoria\/mineralle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/aguaattiva.com.br\/pt_br\/"},{"@type":"ListItem","position":2,"name":"Mineralle"}]},{"@type":"WebSite","@id":"https:\/\/aguaattiva.com.br\/#website","url":"https:\/\/aguaattiva.com.br\/","name":"Agua Mineral Natural Attiva","description":"\u00c1gua Mineral Attiva \u00e9 sin\u00f4nimo de pureza, qualidade e compromisso com a sa\u00fade e bem-estar dos nossos consumidores. Extra\u00edda de fontes cuidadosamente protegidas, nossa \u00e1gua passa por rigorosos controles de qualidade para garantir um produto leve, refrescante e naturalmente equilibrado em sais minerais.  Atuamos no mercado com responsabilidade ambiental e excel\u00eancia em cada etapa da produ\u00e7\u00e3o e distribui\u00e7\u00e3o. Oferecemos uma linha completa para atender diferentes necessidades: 510ml, 1500ml, 5L e 20L, ideal para o dia a dia, empresas, eventos e estabelecimentos comerciais.  Nossa miss\u00e3o \u00e9 levar hidrata\u00e7\u00e3o de qualidade a todos os lares, com respeito \u00e0 natureza e dedica\u00e7\u00e3o ao cliente. Acreditamos que cuidar da sua sa\u00fade come\u00e7a com uma escolha simples: beber bem, beber Attiva.","publisher":{"@id":"https:\/\/aguaattiva.com.br\/#organization"},"alternateName":"Agua Attiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aguaattiva.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"},{"@type":"Organization","@id":"https:\/\/aguaattiva.com.br\/#organization","name":"Attiva Group","url":"https:\/\/aguaattiva.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/aguaattiva.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/agua_attiva-400-e1694737808635.png","contentUrl":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/agua_attiva-400-e1694737808635.png","width":400,"height":400,"caption":"Grupo Attiva"},"image":{"@id":"https:\/\/aguaattiva.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AguaAttiva","https:\/\/www.instagram.com\/aguaattiva\/"]}]}},"_links":{"self":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/categoria\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/categoria"}],"about":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/taxonomies\/categoria"}],"wp:post_type":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/produtos?categoria=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}