{"id":514,"date":"2023-09-14T17:01:16","date_gmt":"2023-09-14T20:01:16","guid":{"rendered":"https:\/\/aguaattiva.com.br\/?post_type=produtos&#038;p=514"},"modified":"2024-09-20T16:51:59","modified_gmt":"2024-09-20T19:51:59","slug":"agua-mineral-510-c-g","status":"publish","type":"produtos","link":"https:\/\/aguaattiva.com.br\/en_za\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/","title":{"rendered":"\u00c1gua Mineral 510 C\/G"},"featured_media":191,"parent":516,"menu_order":0,"template":"","meta":[],"categoria":[12,8,14,17],"class_list":["post-514","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria-agua","categoria-attiva","categoria-com-gas","categoria-descartavel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.4 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c1gua Mineral 510 C\/G - aguaattiva.com.br<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aguaattiva.com.br\/en_za\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1gua Mineral 510 C\/G\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aguaattiva.com.br\/en_za\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/\" \/>\n<meta property=\"og:site_name\" content=\"aguaattiva.com.br\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AguaAttiva\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T19:51:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/Attiva-510-cg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/\",\"name\":\"\u00c1gua Mineral 510 C\\\/G - aguaattiva.com.br\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aguaattiva.com.br\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Attiva-510-cg.png\",\"datePublished\":\"2023-09-14T20:01:16+00:00\",\"dateModified\":\"2024-09-20T19:51:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Attiva-510-cg.png\",\"contentUrl\":\"https:\\\/\\\/aguaattiva.com.br\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Attiva-510-cg.png\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/agua-mineral-510-c-g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/aguaattiva.com.br\\\/pt_br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c1gua Mineral 1500 C\\\/G\",\"item\":\"https:\\\/\\\/aguaattiva.com.br\\\/produtos\\\/agua-mineral-1500-c-g\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00c1gua Mineral 510 C\\\/G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#website\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/\",\"name\":\"Agua Mineral Natural Attiva\",\"description\":\"\u00c1gua Mineral Attiva \u00e9 sin\u00f4nimo de pureza, qualidade e compromisso com a sa\u00fade e bem-estar dos nossos consumidores. Extra\u00edda de fontes cuidadosamente protegidas, nossa \u00e1gua passa por rigorosos controles de qualidade para garantir um produto leve, refrescante e naturalmente equilibrado em sais minerais.  Atuamos no mercado com responsabilidade ambiental e excel\u00eancia em cada etapa da produ\u00e7\u00e3o e distribui\u00e7\u00e3o. Oferecemos uma linha completa para atender diferentes necessidades: 510ml, 1500ml, 5L e 20L, ideal para o dia a dia, empresas, eventos e estabelecimentos comerciais.  Nossa miss\u00e3o \u00e9 levar hidrata\u00e7\u00e3o de qualidade a todos os lares, com respeito \u00e0 natureza e dedica\u00e7\u00e3o ao cliente. Acreditamos que cuidar da sua sa\u00fade come\u00e7a com uma escolha simples: beber bem, beber Attiva.\",\"publisher\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#organization\"},\"alternateName\":\"Agua Attiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aguaattiva.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#organization\",\"name\":\"Grupo Attiva\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aguaattiva.com.br\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/agua_attiva-400-e1694737808635.png\",\"contentUrl\":\"https:\\\/\\\/aguaattiva.com.br\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/agua_attiva-400-e1694737808635.png\",\"width\":400,\"height\":400,\"caption\":\"Grupo Attiva\"},\"image\":{\"@id\":\"https:\\\/\\\/aguaattiva.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AguaAttiva\",\"https:\\\/\\\/www.instagram.com\\\/aguaattiva\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c1gua Mineral 510 C\/G - aguaattiva.com.br","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aguaattiva.com.br\/en_za\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/","og_locale":"en_US","og_type":"article","og_title":"\u00c1gua Mineral 510 C\/G","og_url":"https:\/\/aguaattiva.com.br\/en_za\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/","og_site_name":"aguaattiva.com.br","article_publisher":"https:\/\/www.facebook.com\/AguaAttiva","article_modified_time":"2024-09-20T19:51:59+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/Attiva-510-cg.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/","url":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/","name":"\u00c1gua Mineral 510 C\/G - aguaattiva.com.br","isPartOf":{"@id":"https:\/\/aguaattiva.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/#primaryimage"},"image":{"@id":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/#primaryimage"},"thumbnailUrl":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/Attiva-510-cg.png","datePublished":"2023-09-14T20:01:16+00:00","dateModified":"2024-09-20T19:51:59+00:00","breadcrumb":{"@id":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/#breadcrumb"},"inLanguage":"en-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/"]}]},{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/#primaryimage","url":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/Attiva-510-cg.png","contentUrl":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/Attiva-510-cg.png","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/agua-mineral-510-c-g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/aguaattiva.com.br\/pt_br\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/aguaattiva.com.br\/produtos\/"},{"@type":"ListItem","position":3,"name":"\u00c1gua Mineral 1500 C\/G","item":"https:\/\/aguaattiva.com.br\/produtos\/agua-mineral-1500-c-g\/"},{"@type":"ListItem","position":4,"name":"\u00c1gua Mineral 510 C\/G"}]},{"@type":"WebSite","@id":"https:\/\/aguaattiva.com.br\/#website","url":"https:\/\/aguaattiva.com.br\/","name":"Agua Mineral Natural Attiva","description":"\u00c1gua Mineral Attiva \u00e9 sin\u00f4nimo de pureza, qualidade e compromisso com a sa\u00fade e bem-estar dos nossos consumidores. Extra\u00edda de fontes cuidadosamente protegidas, nossa \u00e1gua passa por rigorosos controles de qualidade para garantir um produto leve, refrescante e naturalmente equilibrado em sais minerais.  Atuamos no mercado com responsabilidade ambiental e excel\u00eancia em cada etapa da produ\u00e7\u00e3o e distribui\u00e7\u00e3o. Oferecemos uma linha completa para atender diferentes necessidades: 510ml, 1500ml, 5L e 20L, ideal para o dia a dia, empresas, eventos e estabelecimentos comerciais.  Nossa miss\u00e3o \u00e9 levar hidrata\u00e7\u00e3o de qualidade a todos os lares, com respeito \u00e0 natureza e dedica\u00e7\u00e3o ao cliente. Acreditamos que cuidar da sua sa\u00fade come\u00e7a com uma escolha simples: beber bem, beber Attiva.","publisher":{"@id":"https:\/\/aguaattiva.com.br\/#organization"},"alternateName":"Agua Attiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aguaattiva.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"},{"@type":"Organization","@id":"https:\/\/aguaattiva.com.br\/#organization","name":"Attiva Group","url":"https:\/\/aguaattiva.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/aguaattiva.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/agua_attiva-400-e1694737808635.png","contentUrl":"https:\/\/aguaattiva.com.br\/wp-content\/uploads\/2023\/09\/agua_attiva-400-e1694737808635.png","width":400,"height":400,"caption":"Grupo Attiva"},"image":{"@id":"https:\/\/aguaattiva.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AguaAttiva","https:\/\/www.instagram.com\/aguaattiva\/"]}]}},"_links":{"self":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/produtos\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/types\/produtos"}],"up":[{"embeddable":true,"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/produtos\/516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/media\/191"}],"wp:attachment":[{"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"categoria","embeddable":true,"href":"https:\/\/aguaattiva.com.br\/en_za\/wp-json\/wp\/v2\/categoria?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}